{"id":3300,"date":"2021-08-19T21:24:08","date_gmt":"2021-08-19T21:24:08","guid":{"rendered":"https:\/\/aceriaguadix.com\/?page_id=3300"},"modified":"2021-11-12T21:13:09","modified_gmt":"2021-11-12T21:13:09","slug":"calidad","status":"publish","type":"page","link":"https:\/\/aceriaguadix.com\/en\/sobre-nosotros\/calidad\/","title":{"rendered":"Calidad"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3300\" class=\"elementor elementor-3300\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-3146d189 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3146d189\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3a104081\" data-id=\"3a104081\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfe6831 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"bfe6831\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/aceriaguadix.com\/wp-content\/uploads\/2021\/11\/aceriaguadix-Calidad-00.jpg\" alt=\"aceriaguadix-Calidad-00\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/aceriaguadix.com\/wp-content\/uploads\/2021\/11\/aceriaguadix-Calidad-01.jpg\" alt=\"aceriaguadix-Calidad-01\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/aceriaguadix.com\/wp-content\/uploads\/2021\/11\/aceriaguadix-Calidad-03-1.jpg\" alt=\"aceriaguadix-Calidad-03\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/aceriaguadix.com\/wp-content\/uploads\/2021\/11\/aceriaguadix-Calidad-04-1-1.jpg\" alt=\"aceriaguadix-Calidad-04-\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-64d67296\" data-id=\"64d67296\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e20a8f9 elementor-widget elementor-widget-section_title\" data-id=\"5e20a8f9\" data-element_type=\"widget\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\n<div class=\"pt-section-title-box\">   \n   \t\t<span class=\"pt-section-sub-title\">Nosotros<\/span>     \t<h5 class=\"pt-section-title\">CALIDAD<\/h5>     \t<p class=\"pt-section-description\">La obtenci\u00f3n de la distinci\u00f3n ISO 9001, como respaldo a la calidad, viene a reconocer el esfuerzo permanente de Aceria Guadix S.A. con sus clientes, siempre apuntando a la excelencia y de esta manera avalando el trabajo que se realiza en las instalaciones.   \n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Anterior Siguiente Nosotros CALIDAD La obtenci\u00f3n de la distinci\u00f3n ISO 9001, como respaldo a la calidad, viene a reconocer el esfuerzo permanente de Aceria Guadix S.A. con sus clientes, siempre apuntando a la excelencia y de esta manera avalando el trabajo que se realiza en las instalaciones.<\/p>","protected":false},"author":1,"featured_media":0,"parent":329,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-3300","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/aceriaguadix.com\/en\/wp-json\/wp\/v2\/pages\/3300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aceriaguadix.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aceriaguadix.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aceriaguadix.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aceriaguadix.com\/en\/wp-json\/wp\/v2\/comments?post=3300"}],"version-history":[{"count":40,"href":"https:\/\/aceriaguadix.com\/en\/wp-json\/wp\/v2\/pages\/3300\/revisions"}],"predecessor-version":[{"id":4914,"href":"https:\/\/aceriaguadix.com\/en\/wp-json\/wp\/v2\/pages\/3300\/revisions\/4914"}],"up":[{"embeddable":true,"href":"https:\/\/aceriaguadix.com\/en\/wp-json\/wp\/v2\/pages\/329"}],"wp:attachment":[{"href":"https:\/\/aceriaguadix.com\/en\/wp-json\/wp\/v2\/media?parent=3300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}